{"id":384552,"date":"2025-09-08T09:01:35","date_gmt":"2025-09-08T09:01:35","guid":{"rendered":"https:\/\/dev.codekraft.it\/rotary-2024\/products\/uncategorized\/alineador-de-ruedas-ccd-speed7080pws-3\/"},"modified":"2025-09-08T09:01:35","modified_gmt":"2025-09-08T09:01:35","slug":"alineador-de-ruedas-ccd-speed7080pws-3","status":"publish","type":"product","link":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/diagnostico-es\/alineadores-de-ruedas-es\/alineador-de-ruedas-ccd-speed7080pws-3\/","title":{"rendered":"Alineador de ruedas CCD SPEED7080PWS.3"},"content":{"rendered":"<p>Alineadores de ruedas equipados con sensores CCD con transmisi\u00f3n de datos Bluetooth y alimentados por bater\u00edas de carga r\u00e1pida. El armario con ruedas permite una gran movilidad entre varios puestos de trabajo gracias a la ausencia de cables.<\/p>\n<ul>\n<li>Eco Cabinet: armario realizado con material respetuoso con el medio ambiente<\/li>\n<li>Dise\u00f1o compacto: detectores CCD extraligeros con un peso de s\u00f3lo 2,6 kg, &#8211; un 30 % inferior al modelo anterior<\/li>\n<li>Tecnolog\u00eda inteligente: software con gr\u00e1ficos actualizados, interfaz de usuario intuitiva, animaciones y ayudas para el ajuste que permiten un trabajo r\u00e1pido y eficaz<\/li>\n<\/ul>\n<ul>\n<li>Detectores con teclado para el control remoto.<\/li>\n<li>La consola sobre ruedas contiene el PC, la impresora y el monitor.<\/li>\n<li>Alimentaci\u00f3n por bater\u00edas recargables de larga duraci\u00f3n.<\/li>\n<li>Transmisi\u00f3n por infrarrojos entre detectores; eficaz incluso en condiciones de poca luz.<\/li>\n<li>Pr\u00e1ctico compartimento para las garras y accesorios.<\/li>\n<li>Amplificadores sin\u00f3pticos de se\u00f1al con LEDs situados en cada detector.<\/li>\n<\/ul>\n<ul>\n<li>Il modello equipados con garras de 3 puntos (STDA35E) permite omitir el procedimiento de compensaci\u00f3n del alabeo, agilizando el trabajo del operario y maximizando la eficiencia del taller.<\/li>\n<li>Procedimiento de giros de la direcci\u00f3n realizado electr\u00f3nicamente mediante sensores CCD para obtener el valor de incidencia, inclinaci\u00f3n y avance de la barra de suspensi\u00f3n con gran precisi\u00f3n.<\/li>\n<li>El programa Spoiler, espec\u00edfico para coches deportivos de perfil bajo, interviene autom\u00e1ticamente y permite la medici\u00f3n sin necesidad de accesorios.<\/li>\n<li>En funci\u00f3n de la altura del chasis, el programa modifica autom\u00e1ticamente la base de datos del alineador de las ruedas.<\/li>\n<li>El programa Movie, mediante gr\u00e1ficos animados en 3D, ayuda al usuario a visualizar la secuencia de operaciones que debe realizar para registrar correctamente el veh\u00edculo.<\/li>\n<li>El r\u00e1pido diagn\u00f3stico del desalineamiento del chasis permite detectar posibles problemas de carrocer\u00eda o de desplazamiento del eje trasero.<\/li>\n<li>Programa de gesti\u00f3n y visualizaci\u00f3n de datos en entorno Microsoft Windows.<\/li>\n<li>Base de datos con m\u00e1s de 90000 fichas t\u00e9cnicas de veh\u00edculos.<\/li>\n<li>Posibilidad de introducci\u00f3n manual de nuevos coches por parte del usuario.<\/li>\n<li>Base de datos de clientes con registro de 20000 operaciones y funci\u00f3n de b\u00fasqueda por nombre o n\u00famero de matr\u00edcula del veh\u00edculo.<\/li>\n<li>Posibilidad de utilizar el programa de compensaci\u00f3n del alabeo empujando el veh\u00edculo 30\u00b0 (compensaci\u00f3n de descentramiento r\u00e1pida y ocupando poco espacio) sin necesidad de elevar el veh\u00edculo.<\/li>\n<li>Compatibles con:\n<ul>\n<li>Sistema TEq-Link Connected Workshop: una plataforma de software para conectar equipos en el taller y supervisar su uso, gestionar el mantenimiento preventivo, enviar informes por correo electr\u00f3nico y mucho m\u00e1s.<\/li>\n<li>Sistemas de calibraci\u00f3n de sensores ADAS (sistemas avanzados de asistencia al conductor).<\/li>\n<li>Shoot &amp; Go: tokens para consultar la base de datos de coches en l\u00ednea. (Disponible en los siguientes pa\u00edses: Dinamarca, Holanda, Alemania (KBA), Suecia, Italia, Espa\u00f1a, Portugal, Irlanda, Nueva Zelanda, Australia, Noruega, Finlandia. (Los modelos pueden variar en funci\u00f3n del pa\u00eds.))<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dispositivo de alineaci\u00f3n de ruedas 8-CCD | incl. garras de 3 puntos, consola cerrada, platos giratorios y LCD pantalla 22\u2033 | Rojo (RAL 3002) | 1 x 230 V \/ 50 &#8211; 60 Hz<\/p>\n","protected":false},"featured_media":356057,"template":"","meta":[],"product_brand":[],"product_cat":[1033430],"product_tag":[1034203,1034169,1034186],"product_approvals":[],"product_application":[],"class_list":{"0":"post-384552","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alineadores-de-ruedas-es","7":"product_tag-motor-homes-es","8":"product_tag-passenger-cars-es","9":"product_tag-light-commercial-es","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"approvals":[],"application":[],"brb_media_brochure":[{"id":380108,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528221_wheel-aligner-speed8050-7080-7060-br-de-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br de 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528221_wheel-aligner-speed8050-7080-7060-br-de-2024-07-screen-pdf-106x150.png","description":""},{"id":380109,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528222_wheel-aligner-speed8050-7080-7060-br-en-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br en 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528222_wheel-aligner-speed8050-7080-7060-br-en-2024-07-screen-pdf-106x150.png","description":""},{"id":380110,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528223_wheel-aligner-speed8050-7080-7060-br-fr-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br fr 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528223_wheel-aligner-speed8050-7080-7060-br-fr-2024-07-screen-pdf-106x150.png","description":""},{"id":380111,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528224_wheel-aligner-speed8050-7080-7060-br-it-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br it 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528224_wheel-aligner-speed8050-7080-7060-br-it-2024-07-screen-pdf-106x150.png","description":""},{"id":380112,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528225_wheel-aligner-speed8050-7080-7060-br-es-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br es 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528225_wheel-aligner-speed8050-7080-7060-br-es-2024-07-screen-pdf-106x150.png","description":""},{"id":380113,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528226_wheel-aligner-speed8050-7080-7060-br-ru-2024-07-screen.pdf","title":"wheel aligner speed8050 7080 7060 br ru 2024 07 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528226_wheel-aligner-speed8050-7080-7060-br-ru-2024-07-screen-pdf-106x150.png","description":""},{"id":384537,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528153_wheel-aligner-ccd-accessories-speed7080-de-screen.pdf","title":"wheel aligner ccd accessories speed7080 de screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528153_wheel-aligner-ccd-accessories-speed7080-de-screen-pdf-106x150.png","description":""},{"id":384538,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528154_wheel-aligner-ccd-accessories-speed7080-en-screen.pdf","title":"wheel aligner ccd accessories speed7080 en screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528154_wheel-aligner-ccd-accessories-speed7080-en-screen-pdf-106x150.png","description":""},{"id":384539,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528156_wheel-aligner-ccd-accessories-speed7080-fr-screen.pdf","title":"wheel aligner ccd accessories speed7080 fr screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528156_wheel-aligner-ccd-accessories-speed7080-fr-screen-pdf-106x150.png","description":""},{"id":384540,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528157_wheel-aligner-ccd-accessories-speed7080-it-screen.pdf","title":"wheel aligner ccd accessories speed7080 it screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528157_wheel-aligner-ccd-accessories-speed7080-it-screen-pdf-106x150.png","description":""},{"id":384541,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528155_wheel-aligner-ccd-accessories-speed7080-es-screen.pdf","title":"wheel aligner ccd accessories speed7080 es screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528155_wheel-aligner-ccd-accessories-speed7080-es-screen-pdf-106x150.png","description":""},{"id":384542,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528158_wheel-aligner-ccd-accessories-speed7080-ru-screen.pdf","title":"wheel aligner ccd accessories speed7080 ru screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528158_wheel-aligner-ccd-accessories-speed7080-ru-screen-pdf-106x150.png","description":""}],"brb_media_drawing":"","brb_media_manuals":[{"id":380120,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00539672_wheel-aligner-ravtd185-rav178-ravtd176-ravtd508-ravtd506-rotsp805-rotsp708-rotsp706-rotsp608-rotsp606-spaarn84-spaarc78-spaarc76-spaars68-spaars66-im-2015-m361-00_vsg_rev00_multi-2024-03pdf.pdf","title":"wheel aligner ravtd185 rav178 ravtd176 ravtd508 ravtd506 rotsp805 rotsp708 rotsp706 rotsp608 rotsp606 spaarn84 spaarc78 spaarc76 spaars68 spaars66 im 2015 m361 00 vsg rev00 multi 2024 03pdf","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00539672_wheel-aligner-ravtd185-rav178-ravtd176-ravtd508-ravtd506-rotsp805-rotsp708-rotsp706-rotsp608-rotsp606-spaarn84-spaarc78-spaarc76-spaars68-spaars66-im-2015-m361-00_vsg_rev00_multi-2024-03pdf-pdf-106x150.png","description":""}],"brb_media_safety_datasheets":"","brb_media_spare_parts":[],"_cdmm_p_id":"503965","_company":"Elektron","_gtin":"5063084700681","accessories":[{"id":381419,"mpn":"STDA33EU","name":"Garras de ruedas 4 puntos | \u00d8 llanta 10 \u2013 24\u2033","description":"Garras autocentrantes a 4 puntos de apoyo | incl. u\u00f1as desmontables | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528317_wheel-aligner-stda33eu-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/garras-de-ruedas-4-puntos-o-llanta-10-24%e2%80%b3\/"},{"id":383371,"mpn":"STDA37","name":"Garras de ruedas para llantas BMW\/Mercedes | \u00d8 neumatico 480 \u2013 915 mm","description":"Garras de apoyo especiales para alineadores de ruedas | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528320_wheel-aligner-stda37-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/garras-de-ruedas-para-llantas-bmw-mercedes-o-neumatico-480-915-mm\/"},{"id":381431,"mpn":"STDA155","name":"Carro para garras de rueda","description":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00519872_wheel-aligner-stda155-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/carro-para-garras-de-rueda\/"},{"id":381760,"mpn":"S110A7\/P","name":"Platos giratorios Standard","description":"\u00d8 300 mm | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00509912_wheel-aligner-s110a7-p-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/platos-giratorios-standard\/"},{"id":381771,"mpn":"STDA124","name":"Platos giratorios Premium STDA124","description":"HD | \u00d8 360 mm | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00509909_wheel-aligner-stda124-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/platos-giratorios-premium-stda124\/"},{"id":383340,"mpn":"STDA71","name":"Garras de ruedas para llantas Porsche | \u00d8 neumatico 380 \u2013 810 mm","description":"Garras de apoyo, incl. abrazaderas y 2+ 2 adaptadores | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528327_wheel-aligner-stda71-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/garras-de-ruedas-para-llantas-porsche-o-neumatico-380-810-mm\/"},{"id":381438,"mpn":"STDA156","name":"Paneles de pared para porta de ruedas | 2 piezas","description":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528346_wheel-aligner-stda156-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/paneles-de-pared-para-porta-de-ruedas-2-piezas\/"},{"id":381445,"mpn":"STDA157","name":"Soportes de pared para porta de ruedas | 4 piezas","description":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528347_wheel-aligner-stda157-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/soportes-de-pared-para-porta-de-ruedas-4-piezas\/"},{"id":380423,"mpn":"S110A2","name":"Placas deslizantes 300 x 225 x 35 mm","description":"1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528308_wheel-aligner-s110a2-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/placas-deslizantes-300-x-225-x-35-mm\/"},{"id":381451,"mpn":"STDA16","name":"Placas deslizantes 1100 x 500 x 50 mm","description":"1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00495705_wheel-aligners-bu-td20wifi-sliding-plates-1100x500x50mm-di-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/placas-deslizantes-1100-x-500-x-50-mm\/"},{"id":381611,"mpn":"STDA17","name":"Placas deslizantes 1500 x 500 x 50 mm","description":"1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528315_wheel-aligner-stda17-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/placas-deslizantes-1500-x-500-x-50-mm\/"},{"id":379807,"mpn":"STDA23\/BTH","name":"Calibre de nivel y de altura","description":"Calibre de nivel y de altura (opci\u00f3n)","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528316_wheel-aligner-stda23-bth-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/calibre-de-nivel-y-de-altura\/"},{"id":383741,"mpn":"STDA163","name":"Kit de calibraci\u00f3n Standard | para serie WS y WD","description":"Solo para serie WS y WD, reemplaza STDA14","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00513153_wheel-aligner-stda163-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/kit-de-calibracion-standard-para-serie-ws-y-wd\/"},{"id":381711,"mpn":"STDA165","name":"Imanes para soporte de las garras | 1 juego","description":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528349_wheel-aligner-stda165-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/imanes-para-soporte-de-las-garras-1-juego\/"},{"id":380637,"mpn":"STDA38","name":"Grupos de bloqueo r\u00e1pido STDA38","description":"para actualizar las garras de ruedas de 4 puntos STDA33EU-34E en garras en apoyo STDA46EU-35E | evita los procedimientos de alabeo | incl. puntales en ABS | \u00d8 neumatico 480 - 760 mm | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528321_wheel-aligner-stda38-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/grupos-de-bloqueo-rapido-stda38\/"},{"id":381675,"mpn":"STDA38K","name":"Grupos de bloqueo r\u00e1pido STDA38K","description":"para actualizar las garras de ruedas de 4 puntos STDA33EU-34E en garras en apoyo STDA46EU-35E | evita los procedimientos de alabeo | incl. puntales en ABS | \u00d8 neumatico 480 - 760 mm | 2 juegos \/ 4 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00509911_wheel-aligner-stda38k-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/grupos-de-bloqueo-rapido-stda38k\/"},{"id":381624,"mpn":"STDA100","name":"Abrazaderas","description":"Para garras en apoyo STDA3E-95E y grupo de bloqueo STDA38 | ancho mediano | \u00d8 neumatico 680 - 910 mm | 1 juego \/ 4 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528330_wheel-aligner-stda100-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/abrazaderas\/"},{"id":381631,"mpn":"STDA101","name":"Abrazaderas","description":"Para garras en apoyo STDA3E-95E y grupo de bloqueo STDA38 | ancho grande | \u00d8 neumatico 860 - 1115 mm | 1 juego \/ 4 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528331_wheel-aligner-stda101-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/abrazaderas-2\/"},{"id":383185,"mpn":"STDA39","name":"U\u00f1as ABS, c\u00f3nicas","description":"Dedos de pl\u00e1stico para garras de rueda STDA46EU-48E-35E-95E | 1 juego \/ 8 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528322_wheel-aligner-stda39-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/unas-abs-conicas\/"},{"id":381637,"mpn":"STDA94","name":"U\u00f1as ABS, perfil reducido","description":"Dedos de pl\u00e1stico para garras de rueda STDA46EU-48E-35E-95E | 1 juego \/ 8 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00506511_stda94-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/unas-abs-perfil-reducido\/"},{"id":383421,"mpn":"STDA143","name":"U\u00f1as ABS, perfil liso","description":"Dedos de pl\u00e1stico para garras de rueda STDA46EU-48E-35E-95E | 1 juego \/ 8 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528339_wheel-aligner-stda143-mi.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/unas-abs-perfil-liso\/"},{"id":379821,"mpn":"STDA131","name":"U\u00f1as para llantas VW | ABS","description":"Dedos de pl\u00e1stico | 1 juego \/ 8 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528332_wheel-aligner-stda131-mi-118x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/unas-para-llantas-vw-abs\/"},{"id":383674,"mpn":"STDA136","name":"U\u00f1as para neum\u00e1ticos de perfil bajo | Metal","description":"Dedos especiales de acero para garras de rueda de 3 y 4 puntos sin abrazaderas | 1 juego \/ 8 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528333_wheel-aligner-stda136-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/unas-para-neumaticos-de-perfil-bajo-metal\/"},{"id":383495,"mpn":"STDA140","name":"Sede para platos mec\u00e1nicos | platos no incluidos | 1 juego","description":"Para RAV4350, RAV4401, RAV4405L, RAV4501L, RAV4651L, RAV4800","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00535627_4-post-lifts-stda140-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/accesorios-elevadores-de-4-columnas-es\/sede-para-platos-mecanicos-platos-no-incluidos-1-juego\/"},{"id":379814,"mpn":"STDA141","name":"Token Aligner Connect","description":"Pantalla remota en un dispositivo m\u00f3vil | utilizo APP desde control remoto","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528337_wheel-aligner-stda141-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/token-aligner-connect-5\/"},{"id":383166,"mpn":"STDA142","name":"Juego access point para utilizo APP desde control remoto","description":"Punto de acceso Wi-Fi | STDA141 requerido","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528338_wheel-aligner-stda142-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/juego-access-point-para-utilizo-app-desde-control-remoto\/"},{"id":383452,"mpn":"STDA154","name":"Adaptadores para garras de 3 puntos para alinear en 2 columnas con alineador CCD | -120 mm","description":"Permite posicionar los cabezales de medici\u00f3n a mayor profundidad y as\u00ed evita interferencias en la transmisi\u00f3n causadas por los brazos elevadores de 2 columnas | 1 juego \/ 4 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528344_wheel-aligner-stda154-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/adaptadores-para-garras-de-3-puntos-para-alinear-en-2-columnas-con-alineador-ccd-120-mm\/"},{"id":383321,"mpn":"STDA68W","name":"Cable de alimentaci\u00f3n de emergencia","description":"De un captador \/ de Serie WS | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528326_wheel-aligner-stda68w-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/cable-de-alimentacion-de-emergencia\/"},{"id":380630,"mpn":"STDA76W","name":"Cables de conexi\u00f3n de emergencia","description":"Suministro el\u00e9ctrico de emergencia y transmisi\u00f3n de datos | para la serie Bluetooth | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528328_wheel-aligner-stda76w-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/cables-de-conexion-de-emergencia\/"},{"id":381736,"mpn":"TEq-Link","name":"Software de conectividad del taller TEq-Link","description":"Software para conectar equipos en el taller y supervisar su uso, gestionar el mantenimiento preventivo, enviar informes por correo electr\u00f3nico y mucho m\u00e1s.","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00409445-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/diagnostico-es\/connected-workshop-es\/software-de-conectividad-del-taller-teq-link\/"},{"id":381682,"mpn":"STDA141ADAS","name":"Token","description":"Habilitaci\u00f3n de la aplicaci\u00f3n para las funciones ADAS (Advanced Driver Assistance Systems)","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528336_wheel-aligner-stda141adas-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/token-5\/"},{"id":383116,"mpn":"STDA150AU","name":"Mordazas para aplicaci\u00f3n paneles ADAS (Autel)","description":"Accesorio de alineadores de ruedas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528341_wheel-aligner-stda150au-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/mordazas-para-aplicacion-paneles-adas-autel\/"},{"id":381984,"mpn":"STDA150TX","name":"Juego de adaptadores para montar los paneles\/captadores en el panel de TEXA","description":"Aplicable cuando ya se posea un sistema ADAS de TEXA","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528342_wheel-aligner-stda150tx-mi.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/juego-de-adaptadores-para-montar-los-paneles-captadores-en-el-panel-de-texa\/"},{"id":383123,"mpn":"STDA150VW","name":"Mordazas para aplicaci\u00f3n paneles ADAS (VAS6430 VW)","description":"Accesorio de alineadores de ruedas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528343_wheel-aligner-stda150vw-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/mordazas-para-aplicacion-paneles-adas-vas6430-vw\/"},{"id":383766,"mpn":"STDAWISHBONE","name":"Token","description":"Activaci\u00f3n del programa de ajuste de la suspensi\u00f3n de doble horquilla \u00abDouble Wishbone\u00bb","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528351_wheel-aligner-stdawishbone-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/token-23\/"},{"id":381698,"mpn":"STDAShoot","name":"Token","description":"Clave virtual para la consulta de base de datos en l\u00ednea a trav\u00e9s de la consulta de la Oficina Federal de Veh\u00edculos Motorizados (KBA) de Alemania | incl. 200 consultas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00510471_wheel-aligners-shootgo-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/token-10\/"},{"id":380104,"mpn":"STDAS200","name":"Cr\u00e9dito de consulta de base de datos Shoot & Go 200","description":"Paquete de cr\u00e9ditos para consultar la base de datos en l\u00ednea a trav\u00e9s de la consulta de la Oficina Federal de Veh\u00edculos Motorizados (KBA) de Alemania | 200 consultas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00510471_wheel-aligners-shootgo-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/credito-de-consulta-de-base-de-datos-shoot-go-200\/"},{"id":380689,"mpn":"STDAS500","name":"Cr\u00e9dito de consulta de base de datos Shoot & Go 500","description":"Paquete de cr\u00e9ditos para consultar la base de datos en l\u00ednea a trav\u00e9s de la consulta de la Oficina Federal de Veh\u00edculos Motorizados (KBA) de Alemania | 500 consultas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00510471_wheel-aligners-shootgo-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/credito-de-consulta-de-base-de-datos-shoot-go-500\/"},{"id":385022,"mpn":"VSG.IDC50.701886","name":"Kit de diagn\u00f3stico STDADIAG","description":"IDC5 KIT TEXA - para la alineaci\u00f3n de las ruedas de diagn\u00f3stico | kit para aquellos que s\u00f3lo tienen la alineaci\u00f3n de las ruedas y no tiene ning\u00fan accesorio TEXA","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00527952_wheel-aligners-accessories-stdadiag-all-configurations-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/kit-de-diagnostico-stdadiag\/"},{"id":385028,"mpn":"VSG.SW500.701893","name":"Kit de diagn\u00f3stico STDADIAG\/SW","description":"TEXA IDC5 SW KIT - para la alineaci\u00f3n de las ruedas de diagn\u00f3stico | kit para aquellos que ya tienen dispositivos TEXA (por ejemplo, ADAS RCSS)","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00527953_wheel-aligners-accessories-stdadiag-ws-all-configurations-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/kit-de-diagnostico-stdadiag-sw\/"},{"id":385046,"mpn":"VSG.FC169.701923","name":"Garras de ruedas Fast clamps","description":"Garras de montaje r\u00e1pido | para alineadores CCD, turismo, tama\u00f1o del neum\u00e1tico 21 - 31\", \u00d8 rueda 540 - 780 mm, peso de las garras 3,8 kg (por juego) | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00528115_wheel-aligner-accessories-vsgfc169701923-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/garras-de-ruedas-fast-clamps-2\/"},{"id":385058,"mpn":"STDAS350","name":"Cr\u00e9dito de consulta de base de datos Shoot & Go 350","description":"Paquete de cr\u00e9ditos para consultar la base de datos en l\u00ednea a trav\u00e9s de la consulta de la Oficina Federal de Veh\u00edculos Motorizados (KBA) de Alemania | 350 consultas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00510471_wheel-aligners-shootgo-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-diagnostico-es\/accesorios-alineadores-de-ruedas-es\/credito-de-consulta-de-base-de-datos-shoot-go-350\/"}],"components":[],"related":[],"page_logo_src":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/2026\/04\/rotary-negative-logo.png","pll_sync_post":{},"lang":"es","translations":{"es":384552,"en":384548,"de":384549,"fr":384550,"it":384551,"ru":384553},"_links":{"self":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product\/384552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/media\/356057"}],"wp:attachment":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/media?parent=384552"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_brand?post=384552"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_cat?post=384552"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_tag?post=384552"},{"taxonomy":"product_approvals","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_approvals?post=384552"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_application?post=384552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}