{"id":378705,"date":"2025-12-11T10:11:31","date_gmt":"2025-12-11T10:11:31","guid":{"rendered":"https:\/\/dev.codekraft.it\/rotary-2024\/products\/uncategorized\/gato-de-foso-desplazable-blitz-r-20-15-premium\/"},"modified":"2025-12-11T10:11:31","modified_gmt":"2025-12-11T10:11:31","slug":"gato-de-foso-desplazable-blitz-r-20-15-premium","status":"publish","type":"product","link":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/elevadores-es\/gatos-de-foso-es\/gato-de-foso-desplazable-blitz-r-20-15-premium\/","title":{"rendered":"Gato de foso, desplazable Blitz R 20\/15 Premium"},"content":{"rendered":"<p>Los elevadores de fosa Blitz cautivan por su dise\u00f1o de seguridad concebido de manera sobresaliente combinado con un uso ergon\u00f3mico y c\u00f3modo &#8211; sin compromisos. Esto significa que establecemos est\u00e1ndares para moderna tecnolog\u00eda de elevaci\u00f3n.<\/p>\n<ul>\n<li>Blitz R &#8211; el \u00f3ptimo en conexi\u00f3n con carriles.<\/li>\n<\/ul>\n<ul>\n<li>Uso patentado en ambos lados (opcional)<\/li>\n<li>Velocidad de elevaci\u00f3n 30 % m\u00e1s r\u00e1pida (opcional)<\/li>\n<li>\u00d3ptima Ergonom\u00eda<\/li>\n<li>Fabricado en Alemania &#8211; 125 a\u00f1os de experiencia<\/li>\n<\/ul>\n<ul>\n<li>Uso patentado en ambos lados (opcional) &#8211; El tiempo necesario para acomodar un veh\u00edculo se reduce al m\u00ednimo, ya no necesario dejar la fosa.<\/li>\n<li>Motor de aire de doble accionamiento (opcional) &#8211; permite una velocidad de elevaci\u00f3n un 30 % m\u00e1s alta.<\/li>\n<li>El motor de aire totalmente cubierto facilita la limpieza y reduce el riesgo de lesiones (opcional).<\/li>\n<li>La bandeja de herramientas integrada lleva la herramienta al mec\u00e1nico, no al contrario.<\/li>\n<li>Las poleas de chasis montadas en rodamientos de agujas permiten que el elevador sea movido sin esfuerzo por la fosa.<\/li>\n<li>Bloqueo de rueda para unidad de elevaci\u00f3n y chasis (Versi\u00f3n M y R)<\/li>\n<\/ul>\n<ul>\n<li>Ergo crom\u00e1tico &#8211; Todos los controles de funcionamiento est\u00e1n marcados con color rojo y as\u00ed evitan eficazmente un uso incorrecto.<\/li>\n<li>Chasis ergon\u00f3mico &#8211; El chasis dise\u00f1ado recientemente lleva al mec\u00e1nico m\u00e1s cerca del elevador, y por lo tanto m\u00e1s cerca del veh\u00edculo.<\/li>\n<li>Acabado superficial en 2 capas &#8211; Proceso recubrimiento opulento para una perfecta protecci\u00f3n contra la corrosi\u00f3n.<\/li>\n<li>Dise\u00f1o esbelto &#8211; Con el beneficio de completo ajuste lateral, el m\u00e9todo de construcci\u00f3n a nivel del suelo permite m\u00e1xima libertad de movimiento.<\/li>\n<li>El retorno autom\u00e1tico hidr\u00e1ulico-neum\u00e1tico permite que el pist\u00f3n retorne r\u00e1pidamente con o sin carga.<\/li>\n<li>Cabezales de cilindro extra-largos &#8211; Garantizan \u00f3ptima absorci\u00f3n de fuerzas laterales.<\/li>\n<li>Unidad de elevaci\u00f3n totalmente hidr\u00e1ulica &#8211; Los v\u00e1stagos de pist\u00f3n se roc\u00edan con aceite con cada movimiento de elevaci\u00f3n\/descenso &#8211; \u00a1Sin \u00f3xido en la pared de cilindro ni el v\u00e1stago de pist\u00f3n!<\/li>\n<li>Velocidad de elevaci\u00f3n infinitamente variable &#8211; importante para una elevaci\u00f3n delicada y para el despliegue de unidades de potencia.<\/li>\n<li>El r\u00e1pido elevador hidr\u00e1ulico-neum\u00e1tico asegura una r\u00e1pida puesta en marcha de los v\u00e1stagos de pist\u00f3n hasta el punto de elevaci\u00f3n.<\/li>\n<li>Funcionamiento por pedales de pie &#8211; las manos quedan libres para realizar el trabajo en el veh\u00edculo.<\/li>\n<\/ul>\n<ul>\n<li>Basic: La Entrada en el Mundo del Elevador de Fosa de Blitz con velocidades normales de elevaci\u00f3n y descenso y sin cubierta.<\/li>\n<li>Plus: El dise\u00f1o para el operario concienciado con el presupuesto. Con todas las caracter\u00edsticas, y solo una unidad operativa.<\/li>\n<li>Premium: El elevador de fosa integrado para ergonom\u00eda perfecta en el lugar de trabajo. Con velocidad de elevaci\u00f3n un 30 % mayor y uso por dos lados.<\/li>\n<\/ul>\n<p><strong>SOLUCIONES INDIVIDUALES<\/strong><\/p>\n<p>Ruedas y chasis especiales bajo pedido<\/p>\n","protected":false},"excerpt":{"rendered":"<p>20\/15 t, elevador de 1200 mm, alta velocidad, panel de funcionamiento completamente cubierto, uso por dos lados\u00a0<\/p>\n","protected":false},"featured_media":350203,"template":"","meta":[],"product_brand":[],"product_cat":[1033840],"product_tag":[1034151,1034134,1034203,1034186],"product_approvals":[],"product_application":[],"class_list":{"0":"post-378705","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gatos-de-foso-es","7":"product_tag-buses-es","8":"product_tag-trucks-es","9":"product_tag-motor-homes-es","10":"product_tag-light-commercial-es","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"approvals":[],"application":[],"brb_media_brochure":[{"id":350204,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421286_pit-lift-floor-running-blitz-r-126461-de-2019-08_screen.pdf","title":"pit lift floor running blitz r 126461 de 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421286_pit-lift-floor-running-blitz-r-126461-de-2019-08_screen-pdf-106x150.png","description":""},{"id":350205,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421287_pit-lift-floor-running-blitz-r-126462-en-2019-08_screen.pdf","title":"pit lift floor running blitz r 126462 en 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421287_pit-lift-floor-running-blitz-r-126462-en-2019-08_screen-pdf-106x150.png","description":""},{"id":350206,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421288_pit-lift-floor-running-blitz-r-126463-fr-2019-08_screen.pdf","title":"pit lift floor running blitz r 126463 fr 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421288_pit-lift-floor-running-blitz-r-126463-fr-2019-08_screen-pdf-106x150.png","description":""},{"id":350207,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421289_pit-lift-floor-running-blitz-r-126464-it-2019-08_screen.pdf","title":"pit lift floor running blitz r 126464 it 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421289_pit-lift-floor-running-blitz-r-126464-it-2019-08_screen-pdf-106x150.png","description":""},{"id":350208,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421290_pit-lift-floor-running-blitz-r-126465-es-2019-08_screen.pdf","title":"pit lift floor running blitz r 126465 es 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421290_pit-lift-floor-running-blitz-r-126465-es-2019-08_screen-pdf-106x150.png","description":""},{"id":350209,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421291_pit-lift-floor-running-blitz-r-126466-ru-2019-08_screen.pdf","title":"pit lift floor running blitz r 126466 ru 2019 08 screen","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421291_pit-lift-floor-running-blitz-r-126466-ru-2019-08_screen-pdf-106x150.png","description":""}],"brb_media_drawing":"","brb_media_manuals":[{"id":377313,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550435_floor-running-pit-lift-om-sp-118691-de-2025-06-rev-k.pdf","title":"Floor running pit lift OM SP 118691 de 2025 06 Rev K","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550435_floor-running-pit-lift-om-sp-118691-de-2025-06-rev-k-pdf-106x150.png","description":""},{"id":377314,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550443_floor-running-pit-lift-om-118774-en-2025-03-rev-i.pdf","title":"Floor running pit lift OM 118774 en 2025 03 Rev I","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550443_floor-running-pit-lift-om-118774-en-2025-03-rev-i-pdf-106x150.png","description":""},{"id":377315,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550448_floor-running-pit-lift-om-118778-fr-2024-02-rev-e.pdf","title":"Floor running pit lift OM 118778 fr 2024 02 Rev E","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550448_floor-running-pit-lift-om-118778-fr-2024-02-rev-e-pdf-106x150.png","description":""},{"id":348328,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421662_floor-running-pit-lift-om-118779-it-2019-05-d.pdf","title":"floor running pit lift om 118779 it 2019 05 d","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421662_floor-running-pit-lift-om-118779-it-2019-05-d-pdf-106x150.png","description":""},{"id":348326,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421663_floor-running-pit-lift-om-118777-es-2019-05-d.pdf","title":"floor running pit lift om 118777 es 2019 05 d","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421663_floor-running-pit-lift-om-118777-es-2019-05-d-pdf-106x150.png","description":""},{"id":348329,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421664_floor-running-pit-lift-om-118780-ru-2019-05-d.pdf","title":"floor running pit lift om 118780 ru 2019 05 d","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00421664_floor-running-pit-lift-om-118780-ru-2019-05-d-pdf-106x150.png","description":""},{"id":377316,"url":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550449_floor-running-pit-lift-om-118774-nl-2019-05-d.pdf","title":"Floor running pit lift OM 118774 nl 2019 05 D","mpn":"","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00550449_floor-running-pit-lift-om-118774-nl-2019-05-d-pdf-106x150.png","description":""}],"brb_media_safety_datasheets":"","brb_media_spare_parts":[],"_cdmm_p_id":"331815","_company":"Elektron","_gtin":"4057612223453","accessories":[{"id":377999,"mpn":"3601500","name":"Filtro del agua \/separador","description":"Separador de agua con filtro, ensamblado en f\u00e1brica | para proteger el sistema y la bomba de condensaciones da\u00f1inas | presi\u00f3n de servicio m\u00e1xima 16 bar","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023171_kondensatabscheider_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-compresores-es\/tratamiento-del-aire-comprimido-es\/filtro-del-agua-separador\/"},{"id":377195,"mpn":"3136","name":"Placa de transmisi\u00f3n GA turismos","description":"\u00c1ngulo de ajuste: +\/- 10\u00ba, capacidad de carga 400 kg, espiga \u00d8 35 mm, dimensiones 300 x 240 mm, correa tensora para sujetar la carga, grandes superficies de apoyo de goma | de uso universal para turismos, especialmente indicado para Mercedes-Benz transmisiones autom\u00e1ticas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022512-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/placas-de-transmision-es\/placa-de-transmision-ga-turismos\/"},{"id":377975,"mpn":"3134","name":"Placa de transmisi\u00f3n GA III","description":"\u00c1ngulo de ajuste +\/- 40\u00ba \/ +\/- 17\u00ba, capacidad de carga 1 t, espiga \u00d8 35 mm, dimensiones 400 x 300 mm (ajustables hasta 600 x 400 mm), correa tensora para sujetar la carga","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022508-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/placas-de-transmision-es\/placa-de-transmision-ga-iii\/"},{"id":377969,"mpn":"3135","name":"Placa de transmisi\u00f3n GA IV","description":"\u00c1ngulo de ajuste +\/- 12\u00ba, capacidad de carga 1 t, espiga \u00d8 35 mm, dimensiones 530 x 380 mm, galvanizado de serie, correa tensora para sujetar la carga, grandes superficies de apoyo de goma","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022510_gearbox-plate-ga-iv-mi-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/placas-de-transmision-es\/placa-de-transmision-ga-iv\/"},{"id":377963,"mpn":"3135060","name":"Caballetes de prisma","description":"Para GA IV | 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023007_prismenblocke-fur-ga-iv_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/caballetes-de-prisma\/"},{"id":377174,"mpn":"33789152","name":"Piezas de conexi\u00f3n ZS 50","description":"1,5 t, 50 mm | 1 juego \/ 2 piezas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023160_zs-100-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/piezas-de-conexion-zs-50\/"},{"id":377168,"mpn":"33789151","name":"Pezzi di collegamento ZS 100","description":"1,5 t, 100 mm | 1 set \/ 2 pezzi","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023160_zs-100-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/pezzi-di-collegamento-zs-100-2\/"},{"id":377951,"mpn":"3325910","name":"Taco X","description":"Abrazadera de acero | capacidad de carga 20 t, espiga \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023151_x-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-x-2\/"},{"id":377939,"mpn":"3364000","name":"Taco R","description":"Placa de soporte, almohadilla de goma, redondo | capacidad de carga 15 t, espiga \u00d8 35 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023129_r-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-r-2\/"},{"id":377933,"mpn":"3364001","name":"Taco R","description":"Placa de soporte, almohadilla de goma, redondo | capacidad de carga 15 t, espiga \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023129_r-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-r\/"},{"id":377921,"mpn":"33879060","name":"Taco U","description":"Placa de soporte | capacidad de carga 15 t, espiga \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023141_u_115_ohne-schrift_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-u\/"},{"id":377915,"mpn":"3381908","name":"Taco U 145","description":"Placa de soporte | capacidad de carga 15 t, espiga \u00d8 35 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023143_u_145_ohne-schrift_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-u-145\/"},{"id":377909,"mpn":"3381909","name":"Taco U 175","description":"Placa de soporte | capacidad de carga 15 t, espiga \u00d8 35 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023143_u_145_ohne-schrift_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-u-175\/"},{"id":377903,"mpn":"3381910","name":"Taco U 220","description":"Placa de soporte | capacidad de carga 15 t, espiga \u00d8 35 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023147_u_220_ohne-schrift_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-u-220\/"},{"id":377897,"mpn":"3384009","name":"Taco H","description":"Abrazadera de madera | capacidad de carga 15 t, espiga \u00d8 35 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023123_h-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-h-3\/"},{"id":377891,"mpn":"3384019","name":"Taco H","description":"Abrazadera de madera | capacidad de carga 20 t, espiga \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023123_h-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-h-2\/"},{"id":377879,"mpn":"3330915","name":"Taco P","description":"Placa de soporte, perno | capacidad de carga 15 t, espiga \u00d8 35 mm | soporte especial (pivote de recepci\u00f3n) para la toma de autobuses al chasis | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023127_p-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-p\/"},{"id":377873,"mpn":"3330914","name":"Taco P MAN","description":"Placa de soporte, perno | capacidad de carga 15 t, espiga \u00d8 35 mm | soporte especial para camiones MAN en el eje posterior (pivote de recepci\u00f3n) | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023125_p-man-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/taco-p-man\/"},{"id":377795,"mpn":"3371","name":"Travesa\u00f1o ATK","description":"10 t, espiga \u00d8 55 mm | horquilla de eje delantero, incl. 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023082_atk-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atk-5\/"},{"id":377789,"mpn":"3372","name":"Travesa\u00f1o ATK","description":"15 t, espiga \u00d8 55 mm | horquilla de eje delantero, incl. 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023082_atk-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atk-4\/"},{"id":377783,"mpn":"3373350","name":"Travesa\u00f1o ATK","description":"20 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023082_atk-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atk-3\/"},{"id":377777,"mpn":"3373","name":"Travesa\u00f1o ATK","description":"20 t, espiga \u00d8 55 mm | horquilla de eje delantero, incl. 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023082_atk-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atk-2\/"},{"id":377771,"mpn":"3401","name":"Travesa\u00f1o ATK","description":"30 t, espiga \u00d8 80 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023082_atk-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atk\/"},{"id":377187,"mpn":"3378350","name":"Travesa\u00f1o ATH","description":"1,5 t, espiga \u00d8 35 mm, rango de ajuste 550 - 1200 mm, telesc\u00f3pico de 1 pliegue | incl. 2 tacos y 2 piezas distanciadoras","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023152_ath-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ath\/"},{"id":377181,"mpn":"3350","name":"Travesa\u00f1o ATT 3,2","description":"3,2 t, espiga \u00d8 35 mm, rango de ajuste 630 - 1230 mm, telesc\u00f3pico de 2 pliegues, incl. planchas de transporte | recepci\u00f3n segura en 2 puntos de veh\u00edculos como Mercedes Benz Sprinter, VW - LT 2","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00108011_at32-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-att-32\/"},{"id":377765,"mpn":"3367","name":"Travesa\u00f1o ATS","description":"10 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023084_ats-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ats-4\/"},{"id":377759,"mpn":"3368","name":"Travesa\u00f1o ATS 15","description":"15 t, espiga \u00d8 55 mm | traviesa est\u00e1ndar de cami\u00f3n | incl. 2 piezas corredizas, 2 tacos y 2 piezas distanciadoras","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023084_ats-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ats-15\/"},{"id":377753,"mpn":"3369350","name":"Travesa\u00f1o ATS","description":"20 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023084_ats-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ats-3\/"},{"id":377735,"mpn":"3330200","name":"Travesa\u00f1o ATB","description":"10 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023078_atb-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atb-2\/"},{"id":377729,"mpn":"3330","name":"Travesa\u00f1o ATB","description":"15 t, espiga \u00d8 55 mm | traviesa est\u00e1ndar de autob\u00fas, incl. 2 piezas corredizas y 4 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023078_atb-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atb\/"},{"id":377723,"mpn":"3330950","name":"Juego de travesa\u00f1os ATB | 10 t","description":"10 t, espiga \u00d8 35 mm | juego de accesorios para soporte de camiones | incl. 2 piezas corredizas, 2 tacos y 2 piezas distanciadoras","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023073_atb-lkw-set_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/juego-de-travesanos-atb-10-t\/"},{"id":377717,"mpn":"101326","name":"Juego de travesa\u00f1os ATB","description":"15 t, espiga \u00d8 55 mm | accesorios para soporte de camiones | incl. 2 piezas corredizas, 2 tacos y 2 piezas distanciadoras","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023073_atb-lkw-set_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/juego-de-travesanos-atb\/"},{"id":377711,"mpn":"3489100","name":"Juego de travesa\u00f1os ATB MAN TGA","description":"15 t, espiga \u00d8 55 mm | accesorios para soporte de camiones MAN en los ejes | incl. juego de conexi\u00f3n, 4 tacos y 4 piezas distanciadoras","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00371216_atb-man-tga-set_p-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/juego-de-travesanos-atb-man-tga\/"},{"id":377705,"mpn":"100142","name":"Travesa\u00f1o ATB N","description":"10 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00021318_atb-n-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atb-n\/"},{"id":377699,"mpn":"3366","name":"Travesa\u00f1o ATB NF","description":"10 t, espiga \u00d8 55 mm, rango de ajuste 420 - 1020 mm | adecuado paraautobuses de chasis bajo | incl. corredizas y pernos de recept\u00e1culo ajustables","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023076_atb-nf-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-atb-nf\/"},{"id":377693,"mpn":"102311","name":"Travesa\u00f1o ATEB","description":"11 t, espiga \u00d8 55 mm","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023080_ateb-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ateb\/"},{"id":378585,"mpn":"114514","name":"Travesa\u00f1o ATEB S2","description":"7,5\/15 t, espiga \u00d8 45\/55 mm, rango de ajuste 200 - 620\/830 - 1500 mm | barra transversal especial para sujetar de forma segura los autobuses EvoBus, especialmente la serie CITARO | incl. 4 tacos y 2 corredizas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00103515_ateb-s2-ohne-text-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ateb-s2-2\/"},{"id":377687,"mpn":"108551","name":"Puente de apoyo GS 10","description":"10 t | Universal | para un soporte a prueba de inclinaci\u00f3n del veh\u00edculo - permite seguir utilizando el elevador de foso | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores, 2 tacos, travesa\u00f1os y bandejas de herramientas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023104_gs-mit-rollen_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gs-10\/"},{"id":377681,"mpn":"108552","name":"Puente de apoyo GS 15","description":"15 t | Universal | para un soporte a prueba de inclinaci\u00f3n del veh\u00edculo - permite seguir utilizando el elevador de foso | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores, 2 tacos, travesa\u00f1os y bandejas de herramientas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023104_gs-mit-rollen_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gs-15\/"},{"id":377675,"mpn":"108553","name":"Puente de apoyo GS 20","description":"20 t | Universal | para un soporte a prueba de inclinaci\u00f3n del veh\u00edculo - permite seguir utilizando el elevador de foso | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores, 2 tacos, travesa\u00f1os y bandejas de herramientas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023104_gs-mit-rollen_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gs-20\/"},{"id":377669,"mpn":"108554","name":"Puente de apoyo GS 30","description":"30 t | Universal | para un soporte a prueba de inclinaci\u00f3n del veh\u00edculo - permite seguir utilizando el elevador de foso | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores, 2 tacos, travesa\u00f1os y bandejas de herramientas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023104_gs-mit-rollen_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gs-30\/"},{"id":377663,"mpn":"108556","name":"Puente de apoyo GSB","description":"15 t | superplano, tambi\u00e9n accesible para autobuses de piso bajo | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores y 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023108_gsb-mit-rollen_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gsb\/"},{"id":377657,"mpn":"34951","name":"Puente de apoyo GSB Vario","description":"15 t | extraplano, tambi\u00e9n accesible para autobuses de piso bajo | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores y 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023106_gsb-vario_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gsb-vario\/"},{"id":377651,"mpn":"33679060","name":"Kit de fijaci\u00f3n ATS","description":"10 t, espiga \u00d8 35 mm | para la conexi\u00f3n segura entre el travesa\u00f1o y el puente de apoyo GS","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023149_vs-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/kit-de-fijacion-ats-2\/"},{"id":377645,"mpn":"33679050","name":"Kit de fijaci\u00f3n ATS","description":"30 t, espiga \u00d8 55 mm | para la conexi\u00f3n segura entre el travesa\u00f1o y el puente de apoyo GS","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023149_vs-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/kit-de-fijacion-ats\/"},{"id":377639,"mpn":"3495920","name":"Bloque de apoyo DB","description":"Bloque de madera 100 x 200 x 360 mm, capacidad de carga 15 t | para bajar el travesa\u00f1o al puente de apoyo | 1 unidad","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023088_db-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/bloque-de-apoyo-db\/"},{"id":377633,"mpn":"108561","name":"Paquete de apoyo I","description":"10 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022946_abstutzpaket-i-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-i-5\/"},{"id":377627,"mpn":"108563","name":"Paquete de apoyo I","description":"15 t, espiga \u00d8 55 mm, m\u00f3vil | equipamiento m\u00ednimo de un foso de trabajo | incl. puente de soporte GS, travesa\u00f1o ATS, 2 piezas distanciadora y juego de conexi\u00f3n","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022946_abstutzpaket-i-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-i-4\/"},{"id":377621,"mpn":"108564","name":"Paquete de apoyo I","description":"20 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022946_abstutzpaket-i-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-i-3\/"},{"id":377615,"mpn":"108566","name":"Paquete de apoyo I","description":"20 t, espiga \u00d8 80 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022946_abstutzpaket-i-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-i-2\/"},{"id":377597,"mpn":"108569","name":"Paquete de apoyo II","description":"11 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022948_abstutzpaket-ii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-ii-4\/"},{"id":377603,"mpn":"108571","name":"Paquete de apoyo II","description":"15 t, espiga \u00d8 55 mm, desplazable | equipamiento b\u00e1sico para talleres de camiones con acceso universal para veh\u00edculos | incl. 2 puentes de soporte GS, 2 travesa\u00f1os (ATS, ATK), 2 piezas distanciadora, juego de conexi\u00f3n y 2 tubos distanciadores","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022948_abstutzpaket-ii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-ii-5\/"},{"id":377591,"mpn":"108572","name":"Paquete de apoyo II","description":"20 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022948_abstutzpaket-ii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-ii-3\/"},{"id":377585,"mpn":"108573","name":"Paquete de apoyo II","description":"20 t, espiga \u00d8 80 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022948_abstutzpaket-ii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-ii-2\/"},{"id":377573,"mpn":"108576","name":"Paquete de apoyo III","description":"10 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022950_abstutzpaket-iii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iii-2\/"},{"id":377567,"mpn":"108578","name":"Paquete de apoyo III","description":"15 t, espiga \u00d8 55 mm, desplazable | para empresas de autobuses y transportes (autobuses de piso bajo) | incl. puente de soporte GSB, travesa\u00f1o ATB, 3 tacos y 2 bloques de madera","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022950_abstutzpaket-iii-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iii\/"},{"id":377555,"mpn":"108580","name":"Paquete de apoyo IV","description":"10 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022956_abstutzpaket-iv-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iv-5\/"},{"id":377549,"mpn":"108582","name":"Paquete de apoyo IV","description":"15 t, espiga \u00d8 55 mm, desplazable | para talleres de reparaci\u00f3n con acceso universal de veh\u00edculos - especializados en camiones, camiones Unimog, veh\u00edculos de construcci\u00f3n y especiales | incl. 3 travesa\u00f1os (ATK, ATS, ATB), 3 puentes de soporte GS, 2 bloques de madera, 5 tacos, 2 tubos distanciadores y 8 piezas distanciadora","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022956_abstutzpaket-iv-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iv-4\/"},{"id":377543,"mpn":"108583","name":"Paquete de apoyo IV","description":"20 t, espiga \u00d8 55 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022956_abstutzpaket-iv-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iv-3\/"},{"id":377537,"mpn":"108584","name":"Paquete de apoyo IV","description":"20 t, espiga \u00d8 80 mm, desplazable","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022956_abstutzpaket-iv-mit-rollen_ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/paquete-de-apoyo-iv-2\/"},{"id":377987,"mpn":"3134101","name":"Casquillo 55\/35","description":"Espiga \u00d8 55 mm, espigas est\u00e1ndar \u00d8 de los placas de transmisi\u00f3n 35 mm | para elevadores BLITZ con asiento \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022995_buchse_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/casquillo-55-35\/"},{"id":377981,"mpn":"3604103","name":"Casquillo 80\/35","description":"Espiga \u00d8 80 mm, espigas est\u00e1ndar \u00d8 de los placas de transmisi\u00f3n 35 mm | para elevadores BLITZ con asiento \u00d8 80 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022995_buchse_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/casquillo-80-35\/"},{"id":377867,"mpn":"3381901","name":"Tubo distanciadores DR 4","description":"10 t, espiga \u00d8 35 mm, 400 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023090_dr-4-ohne-text_web-54x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-4-2\/"},{"id":378591,"mpn":"3387901","name":"Tubo distanciadores DR 4","description":"15 - 20 t, espiga \u00d8 55 mm, 400 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023090_dr-4-ohne-text_web-54x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-4-3\/"},{"id":377861,"mpn":"103907","name":"Tubo distanciadores DR 4","description":"30 t, espiga \u00d8 80 mm, 400 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023090_dr-4-ohne-text_web-54x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-4\/"},{"id":377855,"mpn":"3381915","name":"Tubo distanciadores DR 6","description":"10 t, espiga \u00d8 35 mm, 600 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023092_dr-6-ohne-text_web-36x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-6-2\/"},{"id":377849,"mpn":"3387915","name":"Tubo distanciadores DR 6","description":"30 t, espiga \u00d8 80 mm, 600 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023092_dr-6-ohne-text_web-36x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-6\/"},{"id":377843,"mpn":"3381904","name":"Pieza distanciadora DS 1","description":"15 t, espiga \u00d8 35 mm, 100 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023096_ds-1-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-1-2\/"},{"id":377837,"mpn":"3387904","name":"Pieza distanciadora DS 1","description":"30 t, espiga \u00d8 55 mm, 100 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023096_ds-1-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-1\/"},{"id":377831,"mpn":"3381903","name":"Pieza distanciadora DS 2","description":"15 t, espiga \u00d8 35 mm, 150 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023096_ds-1-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-2-3\/"},{"id":377825,"mpn":"3387903","name":"Pieza distanciadora DS 2","description":"30 t, espiga \u00d8 55 mm, 150 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023096_ds-1-ohne-text_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-2-2\/"},{"id":377819,"mpn":"33069150","name":"Pieza distanciadora DS 2","description":"30 t, espiga \u00d8 80 mm, 150 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023098_ds-2-ohne-text_web-147x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-2\/"},{"id":377813,"mpn":"33819031","name":"Pieza distanciadora DS 3","description":"15 t, espiga \u00d8 35 mm, 250 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023100_ds-3-ohne-text_web-105x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-3-3\/"},{"id":377807,"mpn":"33879029","name":"Pieza distanciadora DS 3","description":"30 t, espiga \u00d8 55 mm, 250 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023100_ds-3-ohne-text_web-105x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-3-2\/"},{"id":377801,"mpn":"3388902","name":"Pieza distanciadora DS 3","description":"30 t, espiga \u00d8 80 mm, 250 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023100_ds-3-ohne-text_web-105x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/pieza-distanciadora-ds-3\/"},{"id":381015,"mpn":"128100","name":"Travesa\u00f1o ATEB S2 TWIN","description":"7,5 - 15 t, espiga \u00d8 55 mm, rango de ajuste 200 - 620\/830 - 1500 mm | barra transversal especial para sujetar de forma segura los autobuses EvoBus, especialmente la serie CITARO | incl. 4 tacos y 2 corredizas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00489144_128100-mi-150x150.jpg","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-ateb-s2-twin\/"},{"id":379763,"mpn":"124950","name":"Travesa\u00f1o ATT 3,2 C","description":"3,2 t, espiga \u00d8 55 mm, rango de ajuste 868 - 1660 mm, telesc\u00f3pico de 2 pliegues | para turismo y transportadores | incl. taco","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00397018_axle-traverse-att32c_mi_001-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/travesano-att-32-c\/"},{"id":379142,"mpn":"114407","name":"Kit de fijaci\u00f3n ATT 3,2","description":"10 t, espiga \u00d8 35 mm | para la colocaci\u00f3n segura de una carga de eje ATT 3,2 en el puente de soporte GS \/ GSB","thumbnail":"","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/kit-de-fijacion-att-32\/"},{"id":385234,"mpn":"108555","name":"Puente de apoyo GSB","description":"10 t | superplano, tambi\u00e9n accesible para autobuses de piso bajo | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores y 2 tacos","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00023110_gsb_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gsb-2\/"},{"id":380979,"mpn":"108674","name":"Puente de apoyo GSV","description":"15 t, ajustable de 900 - 1180 mm | permite seguir utilizando el elevador de foso | incl. juego de rodillos, 2 dispositivos de empuje, 2 tubos distanciadores, 2 tacos y bandejas de herramientas","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00489142_108674-mi-150x150.jpg","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-apoyo-gsv\/"},{"id":384309,"mpn":"128185","name":"Puente de soporte SPZ-15","description":"","thumbnail":"","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/puente-de-soporte-spz-15\/"},{"id":381027,"mpn":"128439","name":"Ampliaci\u00f3n superficie de paso de fosa SPZ-15","description":"Superficie de paso de fosa como kit de reequipamiento, incl. barandilla acoplable, l\u00e1mina antideslizante y chapa de inserci\u00f3n","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00489146_128439-mi-150x150.jpg","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/ampliacion-superficie-de-paso-de-fosa-spz-15\/"},{"id":379124,"mpn":"112400","name":"Plataforma de apoyo","description":"15 t, m\u00f3vil | para uso en combinaci\u00f3n con soportes en U, cebados y lacados, bajada bajo carga","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00371217_abstutzplattform-15-t-112400-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/sistemas-de-apoyo-es\/plataforma-de-apoyo\/"},{"id":379769,"mpn":"125216","name":"Juego de montaje para travesa\u00f1o ATT 3,2 C","description":"Accesorios opcionales para el transporter montaje, juego de pinzas enchufables recomendado | para coches \/ furgonetas \/ MAN \/ Crafter \/ Sprinter","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00397020_125216_att32c_traverse-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/juego-de-montaje-para-travesano-att-32-c\/"},{"id":379775,"mpn":"124618","name":"Kit de energ\u00eda","description":"Set de potencia neum\u00e1tico con suministro de aire comprimido y separador de condensado, incl. 2 conexiones adicionales de aire comprimido y 1 manguera de aire | espiga \u00d8 35 mm, presi\u00f3n de servicio m\u00e1xima 16 bar | para todos los elevadores con motor neum\u00e1tico - especialmente recomendado para Blitz S15 Vario","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00397019_pit-lift-blitzs15vario-energieset-di-124618-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-compresores-es\/tratamiento-del-aire-comprimido-es\/kit-de-energia\/"},{"id":380495,"mpn":"127284","name":"Dispositivo de empuje para travesa\u00f1o ATS","description":"Versi\u00f3n plana, capacidad de carga 15\u00a0t, altura 35\u00a0mm | 1 unidad","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00438633_pad-for-ats-127284-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-otros-productos-es\/accesorios-herramientas-especiales-es\/dispositivo-de-empuje-para-travesano-ats\/"},{"id":381021,"mpn":"128227","name":"Juego de repuesto de portarrollos","description":"Placa portadora \u00ab8Plus\u00bb como kit de conversi\u00f3n | ideal para instalar y desmontar cajas de cambios | bajada desde 800 kg de carga","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00489145_128227-mi-150x150.jpg","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-otros-productos-es\/accesorios-herramientas-especiales-es\/juego-de-repuesto-de-portarrollos\/"},{"id":380459,"mpn":"114100","name":"Casquillo 55\/45","description":"Espiga \u00d8 55\u00a0mm, espigas est\u00e1ndar \u00d8 de los placas de transmisi\u00f3n 45\u00a0mm | para elevadores BLITZ con asiento \u00d8 55 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022995_buchse_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/casquillo-55-45\/"},{"id":380465,"mpn":"3604102","name":"Casquillo 80\/45","description":"Espiga \u00d8 80\u00a0mm, espigas est\u00e1ndar \u00d8 de los placas de transmisi\u00f3n 45 mm | para elevadores BLITZ con asiento \u00d8 80 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00022995_buchse_web-150x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/casquillo-80-45\/"},{"id":379130,"mpn":"3381914","name":"Tubo distanciadores DR 5","description":"10 t, espiga \u00d8 35 mm, 500 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00355544_dr-5_p-ohne-text-24x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-5\/"},{"id":379136,"mpn":"3387916","name":"Tubo distanciadores DR 5","description":"15 - 30 t, espiga \u00d8 55 mm, 500 mm | 1 pieza","thumbnail":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/brb_media\/00355544_dr-5_p-ohne-text-24x150.png","url":"https:\/\/dev.codekraft.it\/rotary-2024\/es\/productos\/accesorios-elevadores-es\/dispositivos-de-transporte-de-carga-es\/tubo-distanciadores-dr-5-2\/"}],"components":[],"related":[],"page_logo_src":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-content\/uploads\/2026\/04\/rotary-negative-logo.png","pll_sync_post":{},"lang":"es","translations":{"es":378705,"en":378701,"de":378702,"fr":378703,"it":378704,"ru":378706},"_links":{"self":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product\/378705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/media\/350203"}],"wp:attachment":[{"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/media?parent=378705"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_brand?post=378705"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_cat?post=378705"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_tag?post=378705"},{"taxonomy":"product_approvals","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_approvals?post=378705"},{"taxonomy":"product_application","embeddable":true,"href":"https:\/\/dev.codekraft.it\/rotary-2024\/wp-json\/wp\/v2\/product_application?post=378705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}